{"id":2925,"date":"2022-11-17T12:00:45","date_gmt":"2022-11-17T11:00:45","guid":{"rendered":"https:\/\/warchildhood.org\/ba\/?p=2925"},"modified":"2022-11-17T15:17:07","modified_gmt":"2022-11-17T14:17:07","slug":"medjunarodni-dan-tolerancije-2022","status":"publish","type":"post","link":"https:\/\/warchildhood.org\/ba\/medjunarodni-dan-tolerancije-2022\/","title":{"rendered":"Me\u0111unarodni dan tolerancije 2022."},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]<span style=\"font-weight: 400;\">Povodom Me\u0111unarodnog dana tolerancije ju\u010der smo se dru\u017eili sa u\u010denicama i u\u010denicima devetih razreda <strong>O\u0160 \u201cFatima Guni\u0107\u201d<\/strong>, <strong>O\u0160 \u201cD\u017eemaludin \u010cau\u0161evi\u0107\u201d <\/strong>i\u00a0<strong>O\u0160 \u201cHrasno\u201d<\/strong>. S njima je tom prilikom razgovarala inspirativna <strong>Dragana Seferovi\u0107<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Prije planiranog dru\u017eenja i diskusije za u\u010denice i u\u010denike organizovana je <strong>vo\u0111ena tura<\/strong> kroz stalnu postavku Muzeja ratnog djetinjstva, a za \u010diju su realizaciju kori\u0161teni <strong>interaktivni muzejski vodi\u010di<\/strong> dostupni na tabletima. U\u010denice i u\u010denici su potom imali priliku demonstrirati svoje znanje i razmi\u0161ljanja o konceptu tolerancije<strong> u\u010de\u0161\u0107em u kratkom kvizu<\/strong>, te saznati vi\u0161e o Draganinom li\u010dnom iskustvu.<\/span>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; max_width_desktop=&#8221;1500&#215;1200&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;2930&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]<span style=\"font-weight: 400;\">Dragana je zapo\u010dela razgovor osvrtom na razli\u010dite etikete koje joj je dodijelilo dru\u0161tvo, ote\u017eavaju\u0107i na taj na\u010din njen \u017eivotni put. Dijelovi svog identiteta koje je Dragana ovom prilikom izdvojila su oni Romkinje i djeteta bez roditelja, a posebno je naglasila <strong>va\u017enost razumijevanja iskustava koja su druga\u010dija od na\u0161ih vlastitih, ali i njegovanja ljubavi prema sebi,<\/strong> koja dodatno dobija na zna\u010daju u kontekstu suo\u010davanja sa netolerancijom i nerazumijevanjem.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">U\u010denice i u\u010denici su imali priliku postavljati pitanja Dragani, te podijeliti svoja zapa\u017eanja, od kojih se posebno isti\u010de ono <strong>Hamze Pire<\/strong> iz O\u0160 \u201cFatima Guni\u0107\u201d:<\/span>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_single_testimonial testimonial_style=&#8221;small_modern&#8221; color=&#8221;Default&#8221; quote=&#8221;Ja \u010dovje\u010danstvo nekako posmatram kao zvjezdano nebo. Sa\u010dinjavaju ga najrazli\u010ditije zvijezde i svaka ima svoj izgled i polo\u017eaj na nebu, ali sve one sjaje i vrijede jednako.&#8221; name=&#8221;Hamza Piro&#8221; subtitle=&#8221;O\u0160 &#8220;Fatima Guni\u0107&#8220;, Sarajevo&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]<span style=\"font-weight: 400;\">Sve u\u010desnice i u\u010desnici ju\u010dera\u0161njih aktivnosti dobili su olovke iz muzejske suvenirnice, a b<\/span>udu\u0107i da je Hamza najuspje\u0161nije odgovorio na pitanja iz kviza o toleranciji njegov doprinos nagradili smo dodatnim poklon paketom.<\/p>\n<p>Na\u0161e dru\u017eenje zaklju\u010dili smo zajedni\u010dkom fotografijom ispred Muzeja ratnog djetinjstva. Hvala vam![\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_gallery type=&#8221;flexslider_style&#8221; images=&#8221;2931,2927,2936,2935,2937,2934,2939,2929,2928,2940&#8243; onclick=&#8221;link_no&#8221; img_size=&#8221;1500&#215;1200&#8243;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":3,"featured_media":2930,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_titles_title":"Me\u0111unarodni dan tolerancije 2022 - MRD","_seopress_titles_desc":"Povodom ovog va\u017enog datuma u\u010denice i u\u010denici 9. razreda tri osnovne \u0161kole iz Sarajeva obi\u0161li su Muzej ratnog djetinjstva i razgovarali s inspirativnom Draganom Seferovi\u0107.","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"Me\u0111unarodni dan tolerancije 2022 - MRD","_seopress_social_fb_desc":"Povodom ovog va\u017enog datuma u\u010denice i u\u010denici 9. razreda tri osnovne \u0161kole iz Sarajeva obi\u0161li su Muzej ratnog djetinjstva i razgovarali s inspirativnom Draganom Seferovi\u0107.","_seopress_social_fb_img":"https:\/\/warchildhood.org\/ba\/wp-content\/uploads\/2022\/11\/Dan-tolerancije-5.jpg","_seopress_social_fb_img_attachment_id":2930,"_seopress_social_fb_img_width":1365,"_seopress_social_fb_img_height":1023,"_seopress_social_twitter_title":"Me\u0111unarodni dan tolerancije 2022 - MRD","_seopress_social_twitter_desc":"Povodom ovog va\u017enog datuma u\u010denice i u\u010denici 9. razreda tri osnovne \u0161kole iz Sarajeva obi\u0161li su Muzej ratnog djetinjstva i razgovarali s inspirativnom Draganom Seferovi\u0107.","_seopress_social_twitter_img":"https:\/\/warchildhood.org\/ba\/wp-content\/uploads\/2022\/11\/Dan-tolerancije-5.jpg","_seopress_social_twitter_img_attachment_id":2930,"_seopress_social_twitter_img_width":1365,"_seopress_social_twitter_img_height":1023,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"Muzej,Muzej ratnog djetinjstva,Dragana Seferovi\u0107,Tolerancija,Me\u0111unarodni dan tolerancije,Izlo\u017eba,Stalna postavka,Osnovne \u0161kole,interaktivni vodi\u010di","footnotes":""},"categories":[10,8],"tags":[],"class_list":["post-2925","post","type-post","status-publish","format-standard","has-post-thumbnail","category-dogadjaji","category-edukacija"],"_links":{"self":[{"href":"https:\/\/warchildhood.org\/ba\/wp-json\/wp\/v2\/posts\/2925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/warchildhood.org\/ba\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/warchildhood.org\/ba\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/warchildhood.org\/ba\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/warchildhood.org\/ba\/wp-json\/wp\/v2\/comments?post=2925"}],"version-history":[{"count":3,"href":"https:\/\/warchildhood.org\/ba\/wp-json\/wp\/v2\/posts\/2925\/revisions"}],"predecessor-version":[{"id":2943,"href":"https:\/\/warchildhood.org\/ba\/wp-json\/wp\/v2\/posts\/2925\/revisions\/2943"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/warchildhood.org\/ba\/wp-json\/wp\/v2\/media\/2930"}],"wp:attachment":[{"href":"https:\/\/warchildhood.org\/ba\/wp-json\/wp\/v2\/media?parent=2925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/warchildhood.org\/ba\/wp-json\/wp\/v2\/categories?post=2925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/warchildhood.org\/ba\/wp-json\/wp\/v2\/tags?post=2925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}